﻿{"id":8229,"date":"2025-04-02T06:14:00","date_gmt":"2025-04-02T09:14:00","guid":{"rendered":"https:\/\/www.boasaude.com.br\/blogboasaude\/?p=8229"},"modified":"2023-10-30T19:15:57","modified_gmt":"2023-10-30T22:15:57","slug":"bebidas-adocadas-com-acucar-aumentam-o-risco-de-morte-prematura-para-pessoas-com-diabetes-tipo-2","status":"publish","type":"post","link":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/bebidas-adocadas-com-acucar-aumentam-o-risco-de-morte-prematura-para-pessoas-com-diabetes-tipo-2\/","title":{"rendered":"Bebidas ado\u00e7adas com a\u00e7\u00facar aumentam o risco de morte prematura para pessoas com diabetes tipo 2"},"content":{"rendered":"\n<p align=\"justify\">  Um estudo realizado na Harvard  University, nos Estados Unidos, mostrou um risco aumentado de morte prematura  para aqueles com diabetes tipo 2 quando bebidas a\u00e7ucaradas, como refrigerante  ou limonada, s\u00e3o consumidas regularmente com \u00e1gua ou ch\u00e1.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p align=\"justify\"> Durante o estudo, os pesquisadores  analisaram mais de 18 anos de dados de sa\u00fade de 9.252 mulheres e 3.519 homens,  todos diagnosticados com diabetes tipo 2. Os participantes relataram a cada  poucos anos quais bebidas consumiam diariamente. As bebidas ado\u00e7adas com a\u00e7\u00facar  inclu\u00edam refrigerantes, ponche de frutas e limonada. As bebidas ado\u00e7adas  artificialmente inclu\u00edam suco, caf\u00e9, ch\u00e1, leite de vaca com baixo teor de  gordura, leite de vaca integral e \u00e1gua pura.<\/p>\n<p align=\"justify\"> Com cada por\u00e7\u00e3o di\u00e1ria adicional de uma  bebida a\u00e7ucarada, houve um aumento de 8% na mortalidade por todas as causas,  disseram os pesquisadores. Esse n\u00famero diminuiu para aqueles que consumiam  bebidas mais saud\u00e1veis regularmente.<\/p>\n<p align=\"justify\"> O n\u00famero caiu 18% para todas as causas  de mortalidade e 20% para doen\u00e7as cardiovasculares quando os diagnosticados com  diabetes tipo 2 substitu\u00edram uma bebida por dia por caf\u00e9. O risco de morte  prematura caiu 16% para ch\u00e1 e \u00e1gua.<\/p>\n<p align=\"justify\"> Segundo os autores, este foi o primeiro  estudo em larga escala da liga\u00e7\u00e3o entre o consumo de bebidas e a morte  prematura ou doen\u00e7a cardiovascular para aqueles que vivem com diabetes tipo 2,  apesar de estudos anteriores que ligam o consumo de bebidas com a sa\u00fade  cardiovascular, mudan\u00e7a de peso e mortalidade entre o geral popula\u00e7\u00e3o.<\/p>\n<p align=\"justify\"> Fonte: The BMJ. DOI:  10.1136\/bmj-2022-073406. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um estudo realizado na Harvard University, nos Estados Unidos, mostrou um risco aumentado de morte prematura para aqueles com diabetes tipo 2 quando bebidas a\u00e7ucaradas, como refrigerante ou limonada, s\u00e3o consumidas regularmente com \u00e1gua ou ch\u00e1.<\/p>\n","protected":false},"author":3,"featured_media":8233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[478],"tags":[35,65,167,56,1185,53],"_links":{"self":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/8229"}],"collection":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/comments?post=8229"}],"version-history":[{"count":1,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/8229\/revisions"}],"predecessor-version":[{"id":8234,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/8229\/revisions\/8234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/media\/8233"}],"wp:attachment":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/media?parent=8229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/categories?post=8229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/tags?post=8229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}