﻿{"id":810,"date":"2011-10-24T12:04:43","date_gmt":"2011-10-24T14:04:43","guid":{"rendered":"http:\/\/boasaude.uol.com.br\/blogboasaude\/?p=810"},"modified":"2011-10-24T12:04:44","modified_gmt":"2011-10-24T14:04:44","slug":"animais-exoticos-oferecem-riscos-a-saude","status":"publish","type":"post","link":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/animais-exoticos-oferecem-riscos-a-saude\/","title":{"rendered":"Animais ex\u00f3ticos oferecem riscos \u00e0 sa\u00fade"},"content":{"rendered":"<p><a href=\"http:\/\/www.boasaude.com.br\/blogboasaude\/?attachment_id=811\" rel=\"attachment wp-att-811\"><img loading=\"lazy\" class=\"alignleft size-full wp-image-811\" title=\"tigre\" src=\"http:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2011\/10\/tigre.jpg\" alt=\"\" width=\"100\" height=\"67\" \/><\/a>Transformar animais ex\u00f3ticos e selvagens em bichinhos de estima\u00e7\u00e3o pode colocar a sa\u00fade humana em risco. Apenas nos Estados Unidos, desde 1990 ocorreram 1.500 ataques e fugas (dentre outros incidentes) com animais ex\u00f3ticos.<\/p>\n<p>Por\u00e9m, o risco n\u00e3o \u00e9 apenas que o animal fuja do controle e ataque um ser humano. Al\u00e9m dos problemas causados por mordidas e arranh\u00f5es, existem tamb\u00e9m as doen\u00e7as que podem ser transmitidas. R\u00e9pteis, por exemplo, podem causar salmonela e macacos podem carregar o v\u00edrus da herpes B.<\/p>\n<ul>\n<li><a href=\"http:\/\/www.livescience.com\/16667-exotic-pets-attack-ohio.html\" target=\"_blank\">Leia mais sobre animais ex\u00f3ticos em cativeiro em Live Science (em ingl\u00eas)<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"http:\/\/www.bibliomed.com.br\/registration\/subsinfotm.cfm?section_name=news&amp;2=2&amp;CFID=1849237&amp;CFTOKEN=37644005\" target=\"_blank\">Leia sobre doen\u00e7as transmitidas por animais dom\u00e9sticos em Boa Sa\u00fade<\/a><\/li>\n<\/ul>\n<ul>\n<li><a href=\"http:\/\/www.bibliomed.com.br\/registration\/subsinfotm.cfm?section_name=news&amp;2=2&amp;CFID=1849237&amp;CFTOKEN=37644005\" target=\"_blank\">Dividir a cama com animais de estima\u00e7\u00e3o pode ser arriscado, leia em Bibliomed (para assinantes)<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transformar animais ex\u00f3ticos e selvagens em bichinhos de estima\u00e7\u00e3o pode colocar a sa\u00fade humana em risco. Apenas nos Estados Unidos, desde 1990 ocorreram 1.500 ataques e fugas (dentre outros incidentes) com animais ex\u00f3ticos. Por\u00e9m, o risco n\u00e3o \u00e9 apenas que o animal fuja do controle e ataque um ser humano. Al\u00e9m dos problemas causados por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[18,20],"tags":[],"_links":{"self":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/810"}],"collection":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/comments?post=810"}],"version-history":[{"count":3,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/810\/revisions"}],"predecessor-version":[{"id":814,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/810\/revisions\/814"}],"wp:attachment":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/media?parent=810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/categories?post=810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/tags?post=810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}