﻿{"id":6724,"date":"2016-11-23T12:25:33","date_gmt":"2016-11-23T14:25:33","guid":{"rendered":"http:\/\/www.boasaude.com.br\/blogboasaude\/?p=6724"},"modified":"2016-11-23T12:25:33","modified_gmt":"2016-11-23T14:25:33","slug":"etnia-influencia-diretamente-na-probabilidade-de-desenvolver-alergia-alimentar","status":"publish","type":"post","link":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/etnia-influencia-diretamente-na-probabilidade-de-desenvolver-alergia-alimentar\/","title":{"rendered":"Etnia influencia diretamente na probabilidade de desenvolver alergia alimentar"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"http:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2016\/11\/destaque_amendoim.jpg\"><img loading=\"lazy\" class=\"alignright size-medium wp-image-6725\" src=\"http:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2016\/11\/destaque_amendoim-300x191.jpg\" alt=\"destaque_amendoim\" width=\"300\" height=\"191\" srcset=\"https:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2016\/11\/destaque_amendoim-300x191.jpg 300w, https:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2016\/11\/destaque_amendoim-100x64.jpg 100w, https:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2016\/11\/destaque_amendoim.jpg 460w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Estudo realizado por pesquisadores da Universidade Rush, em Chicago, nos Estados Unidos, mostrou as alergias alimentares variam conforme a etnia da crian\u00e7a, sendo que as negras e hisp\u00e2nicas s\u00e3o mais propensas a desenvolver alergias a milho, marisco e peixe quando comparadas a crian\u00e7as brancas.<\/p>\n<p style=\"text-align: justify\"><!--more--><\/p>\n<p style=\"text-align: justify\">O estudo envolveu 817 crian\u00e7as diagnosticadas com alergias alimentares desde o nascimento at\u00e9 os 18 anos, e descobriu que ra\u00e7a e etnia s\u00e3o fatores importantes na forma como as crian\u00e7as s\u00e3o afetadas por alergias alimentares. Em compara\u00e7\u00e3o com crian\u00e7as brancas, as crian\u00e7as negras t\u00eam taxas mais elevadas de asma, eczema e alergias ao trigo e \u00e0 soja.<\/p>\n<p style=\"text-align: justify\">O amendoim foi o al\u00e9rgeno alimentar mais comum entre os tr\u00eas grupos raciais. A \u00fanica alergia alimentar mais comum entre as crian\u00e7as brancas do que entre as crian\u00e7as negras e hisp\u00e2nicas foi de nozes, que incluem am\u00eandoas, castanhas do Brasil\/Par\u00e1, caju e pecans.<\/p>\n<p style=\"text-align: justify\">Crian\u00e7as negras e hisp\u00e2nicas tiveram taxas significativamente mais elevadas de anafilaxia (rea\u00e7\u00f5es graves) induzida pelos alimentos. Al\u00e9m disso, crian\u00e7as negras e hisp\u00e2nicas tinham maior probabilidade de dar entrada em hospitais de pronto-atendimento para tratamento de alergia alimentar.<\/p>\n<p style=\"text-align: justify\">O estudo foi publicado no Journal of Allergy and Clinical Immunology e os pesquisadores ressaltam a necessidade de mais estudos para identificar alergia alimentar e sensibilidades alimentares entre todas as ra\u00e7as e etnias a fim de desenvolver programas educacionais para melhorar o tratamento e preven\u00e7\u00e3o de alergia alimentar em todas as crian\u00e7as.<\/p>\n<p style=\"text-align: justify\">Fonte: Journal of Allergy and Clinical Immunology, 21 de novembro de 2016<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudo realizado por pesquisadores da Universidade Rush, em Chicago, nos Estados Unidos, mostrou as alergias alimentares variam conforme a etnia da crian\u00e7a, sendo que as negras e hisp\u00e2nicas s\u00e3o mais propensas a desenvolver alergias a milho, marisco e peixe quando comparadas a crian\u00e7as brancas.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14],"tags":[217,220,100,218,219],"_links":{"self":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/6724"}],"collection":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/comments?post=6724"}],"version-history":[{"count":1,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/6724\/revisions"}],"predecessor-version":[{"id":6726,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/6724\/revisions\/6726"}],"wp:attachment":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/media?parent=6724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/categories?post=6724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/tags?post=6724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}