﻿{"id":582,"date":"2011-08-29T16:40:23","date_gmt":"2011-08-29T19:40:23","guid":{"rendered":"http:\/\/boasaude.uol.com.br\/blogboasaude\/?p=582"},"modified":"2011-10-17T16:41:04","modified_gmt":"2011-10-17T18:41:04","slug":"spray-de-pimenta-pode-aliviar-problemas-respiratorios","status":"publish","type":"post","link":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/spray-de-pimenta-pode-aliviar-problemas-respiratorios\/","title":{"rendered":"Spray de pimenta pode aliviar problemas respirat\u00f3rios"},"content":{"rendered":"<p><a href=\"http:\/\/www.boasaude.com.br\/blogboasaude\/?attachment_id=583\" rel=\"attachment wp-att-583\"><img loading=\"lazy\" class=\"size-full wp-image-583 alignleft\" title=\"pimenta1\" src=\"http:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2011\/10\/pimenta1.jpg\" alt=\"\" width=\"100\" height=\"81\" \/><\/a>Segundo pesquisadores da Universidade de Cincinnati, nos Estados Unidos, a pimenta pode ser a nova aliada de pessoas com sinusite no tratamento da doen\u00e7a. Isso porque ela cont\u00e9m um ingrediente capaz de diminuir inflama\u00e7\u00f5es nos seios paranasais.<\/p>\n<p>Os pesquisadores desenvolveram um spray nasal a base de Capsicum annum, subst\u00e2ncia encontrada na pimenta. Esse foi testado em 44 pacientes e os resultados mostraram que o spray foi eficaz e seguro em para tratamento para rinite n\u00e3o-al\u00e9rgica.<\/p>\n<ul>\n<li>\n<div><a href=\"http:\/\/www.upi.com\/Health_News\/2011\/08\/28\/Chili-pepper-heat-can-ease-sinus-problems\/UPI-98621314571444\/#ixzz1WPgtWswE\" target=\"_blank\">Leia mais sobre o estudo em UPI (em ingl\u00eas)<\/a><\/div>\n<\/li>\n<li>\n<div><a href=\"http:\/\/boasaude.uol.com.br\/lib\/showdoc.cfm?LibCatID=-1&amp;Search=rinite&amp;LibDocID=5047\">Saiba mais sobre a rinite e a sinusite em Boa Sa\u00fade<\/a><\/div>\n<\/li>\n<li>\n<div><a href=\"http:\/\/www.bibliomed.com.br\/lib\/showdoc.cfm?LibCatID=-1&amp;Search=rinite%20&amp;LibDocID=13845\">Alergias respirat\u00f3rias e asma: como prevenir? Veja em Bibliomed (para assinantes)<\/a><\/div>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Segundo pesquisadores da Universidade de Cincinnati, nos Estados Unidos, a pimenta pode ser a nova aliada de pessoas com sinusite no tratamento da doen\u00e7a. Isso porque ela cont\u00e9m um ingrediente capaz de diminuir inflama\u00e7\u00f5es nos seios paranasais. Os pesquisadores desenvolveram um spray nasal a base de Capsicum annum, subst\u00e2ncia encontrada na pimenta. Esse foi testado [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/582"}],"collection":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/comments?post=582"}],"version-history":[{"count":5,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/582\/revisions"}],"predecessor-version":[{"id":590,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/582\/revisions\/590"}],"wp:attachment":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/media?parent=582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/categories?post=582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/tags?post=582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}