﻿{"id":544,"date":"2011-08-30T16:18:25","date_gmt":"2011-08-30T19:18:25","guid":{"rendered":"http:\/\/boasaude.uol.com.br\/blogboasaude\/?p=544"},"modified":"2011-10-17T16:24:54","modified_gmt":"2011-10-17T18:24:54","slug":"criancas-ansiosas-sao-mais-vulneraveis-ao-bullying","status":"publish","type":"post","link":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/criancas-ansiosas-sao-mais-vulneraveis-ao-bullying\/","title":{"rendered":"Crian\u00e7as ansiosas s\u00e3o mais vulner\u00e1veis ao bullying"},"content":{"rendered":"<p><a href=\"http:\/\/www.boasaude.com.br\/blogboasaude\/?attachment_id=545\" rel=\"attachment wp-att-545\"><img loading=\"lazy\" class=\"size-thumbnail wp-image-545 alignleft\" title=\"6jun\" src=\"http:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2011\/10\/6jun-100x106.jpg\" alt=\"\" width=\"100\" height=\"106\" srcset=\"https:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2011\/10\/6jun-100x106.jpg 100w, https:\/\/www.boasaude.com.br\/blogboasaude\/wp-content\/uploads\/2011\/10\/6jun.jpg 205w\" sizes=\"(max-width: 100px) 100vw, 100px\" \/><\/a>Algumas crian\u00e7as t\u00eam problemas para fazerem amizades, e essa dificuldade de socializa\u00e7\u00e3o pode causar ansiedade. Crian\u00e7as nessa situa\u00e7\u00e3o frequentemente est\u00e3o mais vulner\u00e1veis ao bullying, por terem poucos amigos da sua idade e comportamento diferenciado do das outras crian\u00e7as.<\/p>\n<p>\u201cEntender as amizades de crian\u00e7as retra\u00eddas \u00e9 importante porque elas t\u00eam menos contatos com crian\u00e7as da sua pr\u00f3pria idade. Como as consequ\u00eancias do isolamento podem ser severas, pode ser particularmente importante para jovens retra\u00eddos desenvolverem e participarem de amizades atrav\u00e9s de esportes organizados, encontros com amigos e outras atividades semelhantes\u201d, aconselha o pesquisador Gary Ladd, da Arizona State University (EUA).<\/p>\n<ul>\n<li><a href=\"http:\/\/www.livescience.com\/15831-anxious-children-bully-targets.html\" target=\"_blank\">Leia mais sobre a pesquisa em Live Science (em ingl\u00eas)<\/a><\/li>\n<li><a href=\"..\/..\/lib\/showdoc.cfm?LibCatID=-1&amp;Search=ansiedade&amp;LibDocID=5366\" target=\"_blank\">Leia mais sobre a ansiedade na juventude em Boa Sa\u00fade<\/a><\/li>\n<li><a href=\"http:\/\/www.bibliomed.com.br\/registration\/subsinfotm.cfm?section_name=news&amp;2=2&amp;CFID=1849237&amp;CFTOKEN=37644005\" target=\"_blank\">Leia mais sobre o bullying em Bibliomed (para assinantes)<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Algumas crian\u00e7as t\u00eam problemas para fazerem amizades, e essa dificuldade de socializa\u00e7\u00e3o pode causar ansiedade. Crian\u00e7as nessa situa\u00e7\u00e3o frequentemente est\u00e3o mais vulner\u00e1veis ao bullying, por terem poucos amigos da sua idade e comportamento diferenciado do das outras crian\u00e7as. \u201cEntender as amizades de crian\u00e7as retra\u00eddas \u00e9 importante porque elas t\u00eam menos contatos com crian\u00e7as da sua [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[18],"tags":[],"_links":{"self":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/544"}],"collection":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/comments?post=544"}],"version-history":[{"count":5,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/544\/revisions"}],"predecessor-version":[{"id":564,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/posts\/544\/revisions\/564"}],"wp:attachment":[{"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/media?parent=544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/categories?post=544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.boasaude.com.br\/blogboasaude\/index.php\/wp-json\/wp\/v2\/tags?post=544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}